{"id":97,"count":1,"description":"Discover wonderful places in Turkey - tourist destinations, travel guides, daily itinerary, sights to visit, tips&amp;tricks, costs","link":"https:\/\/pinandtrip.com\/en\/europa\/turcia\/","name":"Turkey","slug":"turcia","taxonomy":"category","parent":63,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri<\/title>\n<meta name=\"description\" content=\"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&amp;tricks, costuri, destinatii, travel blog\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pinandtrip.com\/en\/europa\/turcia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri\" \/>\n<meta property=\"og:description\" content=\"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&amp;tricks, costuri, destinatii, travel blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pinandtrip.com\/en\/europa\/turcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pin &amp; Trip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pinandtrip.com\/europa\/turcia\/\",\"url\":\"https:\/\/pinandtrip.com\/europa\/turcia\/\",\"name\":\"Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri\",\"isPartOf\":{\"@id\":\"https:\/\/pinandtrip.com\/#website\"},\"description\":\"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&tricks, costuri, destinatii, travel blog\",\"breadcrumb\":{\"@id\":\"https:\/\/pinandtrip.com\/europa\/turcia\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pinandtrip.com\/europa\/turcia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pinandtrip.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europa\",\"item\":\"https:\/\/pinandtrip.com\/europa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Turcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pinandtrip.com\/#website\",\"url\":\"https:\/\/pinandtrip.com\/\",\"name\":\"Pin&Trip\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pinandtrip.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri","description":"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&tricks, costuri, destinatii, travel blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pinandtrip.com\/en\/europa\/turcia\/","og_locale":"en_US","og_type":"article","og_title":"Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri","og_description":"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&tricks, costuri, destinatii, travel blog","og_url":"https:\/\/pinandtrip.com\/en\/europa\/turcia\/","og_site_name":"Pin &amp; Trip","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pinandtrip.com\/europa\/turcia\/","url":"https:\/\/pinandtrip.com\/europa\/turcia\/","name":"Turcia - articole de calatorie, idei, destinatii, itinerarii pe zile, costuri","isPartOf":{"@id":"https:\/\/pinandtrip.com\/#website"},"description":"Descopera locuri minunate din Turcia \u2013 ghiduri de calatorie, itinerar pe zile, obiective de vizitat, tips&tricks, costuri, destinatii, travel blog","breadcrumb":{"@id":"https:\/\/pinandtrip.com\/europa\/turcia\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pinandtrip.com\/europa\/turcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pinandtrip.com\/"},{"@type":"ListItem","position":2,"name":"Europa","item":"https:\/\/pinandtrip.com\/europa\/"},{"@type":"ListItem","position":3,"name":"Turcia"}]},{"@type":"WebSite","@id":"https:\/\/pinandtrip.com\/#website","url":"https:\/\/pinandtrip.com\/","name":"Pin&Trip","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pinandtrip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pinandtrip.com\/en\/wp-json\/wp\/v2\/categories\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinandtrip.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pinandtrip.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/pinandtrip.com\/en\/wp-json\/wp\/v2\/categories\/63"}],"wp:post_type":[{"href":"https:\/\/pinandtrip.com\/en\/wp-json\/wp\/v2\/posts?categories=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}